{"id":9,"count":155,"description":"Scienziati, Laboratori, Ricerca, Innovazione \r\nIl Politecnico di Milano apre le porte dei suoi laboratori per raccontare i progetti di ricerca portati avanti da alcuni degli  scienziati migliori al mondo. Questa sezione racconta il contributo dei ricercatori politecnici nella ricerca di frontiera e di base come in quella applicata e industriale, con un occhio puntato ai grandi temi che guidano le trasformazioni scientifiche e tecnologiche della nostra epoca, dalle nanoparticelle ai viaggi spaziali.","link":"https:\/\/alumni.polimi.it\/en\/category\/cat_ricerca\/","name":"Research","slug":"cat_ricerca","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ricerca Archivi - Alumni<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alumni.polimi.it\/en\/category\/cat_ricerca\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ricerca Archivi - Alumni\" \/>\n<meta property=\"og:description\" content=\"Scienziati, Laboratori, Ricerca, Innovazione Il Politecnico di Milano apre le porte dei suoi laboratori per raccontare i progetti di ricerca portati avanti da alcuni degli scienziati migliori al mondo. Questa sezione racconta il contributo dei ricercatori politecnici nella ricerca di frontiera e di base come in quella applicata e industriale, con un occhio puntato ai grandi temi che guidano le trasformazioni scientifiche e tecnologiche della nostra epoca, dalle nanoparticelle ai viaggi spaziali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alumni.polimi.it\/en\/category\/cat_ricerca\/\" \/>\n<meta property=\"og:site_name\" content=\"Alumni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/alumni.polimi.it\\\/category\\\/cat_ricerca\\\/\",\"url\":\"https:\\\/\\\/alumni.polimi.it\\\/category\\\/cat_ricerca\\\/\",\"name\":\"Ricerca Archivi - Alumni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alumni.polimi.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alumni.polimi.it\\\/category\\\/cat_ricerca\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alumni.polimi.it\\\/category\\\/cat_ricerca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alumni.polimi.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricerca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alumni.polimi.it\\\/#website\",\"url\":\"https:\\\/\\\/alumni.polimi.it\\\/\",\"name\":\"Alumni\",\"description\":\"Politecnico di Milano\",\"publisher\":{\"@id\":\"https:\\\/\\\/alumni.polimi.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alumni.polimi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alumni.polimi.it\\\/#organization\",\"name\":\"Alumni Polimi Association\",\"url\":\"https:\\\/\\\/alumni.polimi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alumni.polimi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alumni.polimi.it\\\/wp-content\\\/uploads\\\/Alumni.jpg\",\"contentUrl\":\"https:\\\/\\\/alumni.polimi.it\\\/wp-content\\\/uploads\\\/Alumni.jpg\",\"width\":1000,\"height\":267,\"caption\":\"Alumni Polimi Association\"},\"image\":{\"@id\":\"https:\\\/\\\/alumni.polimi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AlumniPolimi\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/alumni-politecnico-di-milano\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ricerca Archivi - Alumni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alumni.polimi.it\/en\/category\/cat_ricerca\/","og_locale":"en_US","og_type":"article","og_title":"Ricerca Archivi - Alumni","og_description":"Scienziati, Laboratori, Ricerca, Innovazione Il Politecnico di Milano apre le porte dei suoi laboratori per raccontare i progetti di ricerca portati avanti da alcuni degli scienziati migliori al mondo. Questa sezione racconta il contributo dei ricercatori politecnici nella ricerca di frontiera e di base come in quella applicata e industriale, con un occhio puntato ai grandi temi che guidano le trasformazioni scientifiche e tecnologiche della nostra epoca, dalle nanoparticelle ai viaggi spaziali.","og_url":"https:\/\/alumni.polimi.it\/en\/category\/cat_ricerca\/","og_site_name":"Alumni","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/alumni.polimi.it\/category\/cat_ricerca\/","url":"https:\/\/alumni.polimi.it\/category\/cat_ricerca\/","name":"Ricerca Archivi - Alumni","isPartOf":{"@id":"https:\/\/alumni.polimi.it\/#website"},"breadcrumb":{"@id":"https:\/\/alumni.polimi.it\/category\/cat_ricerca\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/alumni.polimi.it\/category\/cat_ricerca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alumni.polimi.it\/"},{"@type":"ListItem","position":2,"name":"Ricerca"}]},{"@type":"WebSite","@id":"https:\/\/alumni.polimi.it\/#website","url":"https:\/\/alumni.polimi.it\/","name":"Alumni","description":"Politecnico di Milano","publisher":{"@id":"https:\/\/alumni.polimi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alumni.polimi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alumni.polimi.it\/#organization","name":"Alumni Polimi Association","url":"https:\/\/alumni.polimi.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alumni.polimi.it\/#\/schema\/logo\/image\/","url":"https:\/\/alumni.polimi.it\/wp-content\/uploads\/Alumni.jpg","contentUrl":"https:\/\/alumni.polimi.it\/wp-content\/uploads\/Alumni.jpg","width":1000,"height":267,"caption":"Alumni Polimi Association"},"image":{"@id":"https:\/\/alumni.polimi.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlumniPolimi\/","https:\/\/www.linkedin.com\/company\/alumni-politecnico-di-milano\/"]}]}},"_links":{"self":[{"href":"https:\/\/alumni.polimi.it\/en\/wp-json\/wp\/v2\/categories\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alumni.polimi.it\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/alumni.polimi.it\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/alumni.polimi.it\/en\/wp-json\/wp\/v2\/posts?categories=9"},{"href":"https:\/\/alumni.polimi.it\/en\/wp-json\/wp\/v2\/ctp_chapter?categories=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}